{"id":8956,"date":"2018-06-05T20:15:32","date_gmt":"2018-06-05T20:15:32","guid":{"rendered":"http:\/\/villasancarlos.club\/vsc\/?p=8956"},"modified":"2018-06-05T20:15:32","modified_gmt":"2018-06-05T20:15:32","slug":"jornada-mas-que-positiva-para-las-inferiores","status":"publish","type":"post","link":"https:\/\/villasancarlos.club\/vsc\/2018\/06\/jornada-mas-que-positiva-para-las-inferiores\/","title":{"rendered":"Jornada m\u00e1s que positiva para las inferiores"},"content":{"rendered":"<p><strong>Con las jornadas de Escuelita, Menores, Formativas y Sub-21, pas\u00f3 otro fin de semana cargado de acci\u00f3n para el b\u00e1squet de Villa San Carlos.<\/strong><\/p>\n<p>El s\u00e1bado por la ma\u00f1ana, la Escuela de B\u00e1squet del &#8220;Cele&#8221; particip\u00f3 del encuentro realizado en cancha de Astillero.<\/p>\n<p>Por la tarde, las categor\u00edas menores recibieron a C\u00edrculo Marchigiano, donde sumaron tres victorias. Los U-15 siguen con puntaje ideal ya que ganaron 79 a 22; en el partido m\u00e1s parejo de la jornada, los U-17 superaron al &#8220;Tano&#8221; 51 a 42; mientras que los U-19 volvieron al triunfo por 107 a 37.<\/p>\n<p>El domingo por la ma\u00f1ana, las categor\u00edas formativas visitaron a Asociaci\u00f3n Mayo. Los pre-mini sumaron su punto de presentaci\u00f3n, por su parte los mini cayeron 43 a 37 y los U-13 obtuvieron un gran triunfo en tiempo suplementario por 54 a 39.<\/p>\n<p>Por su parte, los mini &#8220;B&#8221; tambi\u00e9n se vieron las caras ante Mayo, donde ganaron por 15 puntos pese a no completar.<\/p>\n<p>En \u00faltimo lugar, los Sub-21 llegaron a su sexto triunfo en igual cantidad de presentaciones, al superar 71 a 61 a Centro Fomento Los Hornos, en un partido muy disputado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con las jornadas de Escuelita, Menores, Formativas y Sub-21, pas\u00f3 otro fin de semana cargado de acci\u00f3n para el b\u00e1squet de Villa San Carlos. El s\u00e1bado por la ma\u00f1ana, la Escuela de B\u00e1squet del &#8220;Cele&#8221; particip\u00f3 del encuentro realizado en cancha de Astillero. Por la tarde, las categor\u00edas menores recibieron a C\u00edrculo Marchigiano, donde sumaron [&#8230;]\n","protected":false},"author":1,"featured_media":8971,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[34],"class_list":["post-8956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquet-juvenil","tag-basquet-juvenil"],"_links":{"self":[{"href":"https:\/\/villasancarlos.club\/vsc\/wp-json\/wp\/v2\/posts\/8956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/villasancarlos.club\/vsc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/villasancarlos.club\/vsc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/villasancarlos.club\/vsc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/villasancarlos.club\/vsc\/wp-json\/wp\/v2\/comments?post=8956"}],"version-history":[{"count":3,"href":"https:\/\/villasancarlos.club\/vsc\/wp-json\/wp\/v2\/posts\/8956\/revisions"}],"predecessor-version":[{"id":8967,"href":"https:\/\/villasancarlos.club\/vsc\/wp-json\/wp\/v2\/posts\/8956\/revisions\/8967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/villasancarlos.club\/vsc\/wp-json\/wp\/v2\/media\/8971"}],"wp:attachment":[{"href":"https:\/\/villasancarlos.club\/vsc\/wp-json\/wp\/v2\/media?parent=8956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/villasancarlos.club\/vsc\/wp-json\/wp\/v2\/categories?post=8956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/villasancarlos.club\/vsc\/wp-json\/wp\/v2\/tags?post=8956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}